{"id":29,"date":"2015-04-07T13:27:57","date_gmt":"2015-04-07T11:27:57","guid":{"rendered":"http:\/\/boudoir36.it.5.249.143.141.xip.io\/?page_id=29"},"modified":"2015-11-03T12:11:26","modified_gmt":"2015-11-03T11:11:26","slug":"condizioni-di-vendita","status":"publish","type":"page","link":"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/","title":{"rendered":"Condizioni generali di vendita"},"content":{"rendered":"<ul>\n<li>\n<h3>Disposizioni generali<\/h3>\n<p>Le presenti condizioni sono valide esclusivamente tra la ditta individuale Boudoir 36 di Alessandria Antonino Sebastiano, con sede legale in Via Santa Filomena 36, 95129 Catania, Italia, REA CT-287036, P.IVA 04306840879, C.F. LSSNNN71C30C351R di seguito denominata \u201cBoudoir 36\u201d e qualsiasi persona, di seguito denominata \u201cCLIENTE\u201d, che effettua acquisti online sul sito internet <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a>, accedendovi in maniera diretta o tramite reindirizzamento dal sito <a href=\"http:\/\/www.antonioalessandria.it\">www.antonioalessandria.it<\/a>. Queste condizioni possono essere oggetto di modifiche e la data di pubblicazione delle stesse sul sito equivale alla data di entrata in vigore.<\/p>\n<p>Le presenti condizioni disciplinano gli acquisti effettuati sul sito <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a>, conformemente alle disposizioni della Parte III, Titolo III, Capo I, del Codice del Consumo, D.lgs. n. 206\/2005, modificato dal D.lgs. n. 21\/2014 e dal D.lgs. 70\/2003 in materia di commercio elettronico.<\/li>\n<li>\n<h3>ARTICOLO 1 &#8211; Oggetto del contratto<\/h3>\n<p>Con le presenti condizioni generali di vendita, Boudoir 36 vende e il CLIENTE acquista a distanza i beni mobili materiali indicati ed offerti in vendita sul sito <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a>. Il contratto si conclude attraverso la rete internet, mediante l&#8217;accesso del CLIENTE all&#8217;indirizzo <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a>, o tramite reindirizzamento dal sito <a href=\"http:\/\/www.antonioalessandria.it\">www.antonioalessandria.it<\/a>, e la realizzazione di un ordine di acquisto secondo la procedura prevista dal sito stesso.<\/p>\n<p>Il cliente si impegna a prendere visione, prima di procedere alla conferma del proprio ordine, delle presenti condizioni generali di vendita, in particolare delle informazioni precontrattuali fornite da Boudoir 36. La conferma dell\u2019ordine implica l\u2019accettazione di queste condizioni generali di vendita.<\/p>\n<p>Nella e-mail di conferma dell&#8217;ordine, il CLIENTE ricever\u00e0 anche il link per scaricare ed archiviare una copia delle presenti condizioni generali di vendita, cos\u00ec come previsto dall&#8217;art. 51 comma 1 del D.Lgs 206\/2005, modificato dal D.lgs 21\/2014.<\/li>\n<li>\n<h3>ARTICOLO 2 &#8211; Informazioni precontrattuali per il consumatore &#8211; art. 49 del D.lgs 206\/2005<\/h3>\n<p>Il CLIENTE prima della conclusione del contratto di acquisto, prende visione delle caratteristiche dei beni che vengono illustrate nelle singole schede prodotto al momento della scelta.<\/p>\n<p>Prima della conclusione del contratto di acquisto e prima della convalida dell&#8217;ordine con \u201cobbligo di pagamento\u201d, il CLIENTE \u00e8 informato relativamente a:<\/p>\n<ul style=\"list-style-type: disc; list-style: circle;\">\n<li>Prezzo totale dei beni comprensivo delle imposte, con il dettaglio delle spese di spedizione e ogni altro costo;<\/li>\n<li>Modalit\u00e0 di pagamento;<\/li>\n<li>Il termine entro il quale Boudoir 36 si impegna a consegnare la merce;<\/li>\n<li>Le condizioni, i termini e le procedure per esercitare il diritto di recesso (art. 6 delle presenti condizioni) nonch\u00e9 modulo tipo di recesso di cui all&#8217;allegato I, parte B del D.lgs 21\/2014;<\/li>\n<li>Il fatto che il CLIENTE dovr\u00e0 sostenere il costo della restituzione dei beni in caso di recesso;<\/li>\n<li>Esistenza della garanzia legale di conformit\u00e0 per i beni acquistati;<\/li>\n<li>Condizioni di assistenza post vendita e garanzie commerciali previste da Boudoir 36.<\/li>\n<\/ul>\n<p>Il CLIENTE pu\u00f2 in qualsiasi momento e comunque prima della conclusione del contratto, prendere conoscenza delle informazioni relative a Boudoir 36, l&#8217;indirizzo geografico, numero di telefono, indirizzo di posta elettronica, informazioni che vengono riportate, anche di seguito:<\/p>\n<address>Boudoir 36 di Alessandria Antonino Sebastiano<br \/>\nsede legale Via Santa Filomena, 36<br \/>\n95129 Catania (CT)<br \/>\ntel. <a href=\"tel: +390957152358\">+39 095 7152358<\/a><br \/>\nE-mail <a href=\"mailto:ecommerce@boudoir36.it\">ecommerce@boudoir36.it<\/a><\/address>\n<\/li>\n<li>\n<h3>ARTICOLO 3 &#8211; Conclusione ed efficacia del contratto<\/h3>\n<p>Il contratto di vendita \u00e8 considerato concluso con l&#8217;invio da parte di Boudoir 36 al CLIENTE di un&#8217;e-mail di conferma dell&#8217;ordine. L&#8217;e-mail contiene i dati del CLIENTE e il numero d&#8217;ordine, il prezzo della merce acquistata, le spese di spedizione e l&#8217;indirizzo di consegna al quale sar\u00e0 inviata la merce e il link per poter stampare e archiviare la copia delle presenti condizioni.<\/p>\n<p>Il CLIENTE si impegna a verificare la correttezza dei dati personali in essa contenuti e a comunicare tempestivamente a Boudoir 36 eventuali correzioni.<\/p>\n<p>Boudoir 36 si impegna a descrivere e presentare gli articoli venduti sul sito nel miglior modo possibile. Ciononostante potrebbero evidenziarsi alcuni errori, imprecisioni o piccole differenze tra il sito e il prodotto reale. Inoltre le fotografie dei prodotti presentati su <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a> non costituiscono elemento contrattuale, in quanto solo rappresentative.<\/p>\n<p>Boudoir 36 si impegna a consegnare la merce entro 30 giorni decorrenti dall&#8217;invio da parte di Boudoir 36 dell&#8217;e-mail di conferma d&#8217;ordine al CLIENTE.<\/li>\n<li>\n<h3>ARTICOLO 4 &#8211; Disponibilit\u00e0 dei prodotti<\/h3>\n<p>La disponibilit\u00e0 dei prodotti si riferisce alla disponibilit\u00e0 effettiva nel momento in cui il CLIENTE effettua l&#8217;ordine. Tale disponibilit\u00e0 deve comunque essere considerata puramente indicativa perch\u00e9, per effetto della contemporanea presenza sul sito di pi\u00f9 utenti, i prodotti potrebbero essere venduti ad altri CLIENTI prima della conferma dell&#8217;ordine.<\/p>\n<p>Anche in seguito all&#8217;invio dell&#8217;e-mail di conferma dell&#8217;ordine inviata da Boudoir 36, potrebbero verificarsi casi di indisponibilit\u00e0 parziale o totale della merce. In questa eventualit\u00e0, l&#8217;ordine verr\u00e0 rettificato automaticamente con l&#8217;eliminazione del prodotto non disponibile e il CLIENTE verr\u00e0 immediatamente informato via e-mail.<\/p>\n<p>Se il CLIENTE richiede l&#8217;annullamento dell&#8217;ordine, risolvendo il contratto, Boudoir 36 rimborser\u00e0 l\u2019importo pagato entro 14 giorni dal giorno in cui Boudoir 36 ha avuto conoscenza della decisione del cliente di risolvere il contratto.<\/li>\n<li>\n<h3>ARTICOLO 5 &#8211; Modalit\u00e0 di pagamento<\/h3>\n<p>Ogni pagamento da parte del CLIENTE potr\u00e0 avvenire unicamente per mezzo delle carte di credito indicate sul sito <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a>, con bonifico bancario, con metodo di pagamento Paypal o con pagamento in contanti alla consegna (contrassegno). In caso di pagamento con carta di credito e con Paypal, il CLIENTE verr\u00e0 reindirizzato sulla piattaforma di pagamento Paypal, dove potr\u00e0 effettuare il pagamento in modalit\u00e0 sicura. La piattaforma Paypal gestisce direttamente i dati immessi sul proprio sito Internet per effettuare il pagamento. Boudoir 36 non raccoglie alcun dato relativo alla Carta di Credito utilizzata, o relativo ai codici di accesso alla forma di pagamento &#8220;Paypal&#8221;. Queste informazioni sono raccolte direttamente dal sistema di pagamento Paypal.<\/p>\n<p>Nel caso di pagamento tramite contrassegno, il cliente dovr\u00e0 pagare un supplemento di costo di \u20ac 10,00 (IVA inclusa) per la gestione del contrassegno da parte del corriere espresso. Il pagamento dovr\u00e0 essere effettuato alla consegna, in contanti, direttamente al corriere per un importo non superiore ad \u20ac 999,00. Il corriere non accetta assegni di alcun tipo.<\/li>\n<li>\n<h3>ARTICOLO 6 &#8211; Prezzi<\/h3>\n<p>Tutti i prezzi di vendita dei prodotti indicati sul sito <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a> sono espressi in Euro e sono comprensivi di IVA.<\/p>\n<p>I costi di spedizione non sono compresi nel prezzo d&#8217;acquisto, ma sono indicati e calcolati al momento della conclusione del processo di acquisto prima dell&#8217;effettuazione del pagamento.<\/p>\n<p>Il CLIENTE accetta la facolt\u00e0 di Boudoir 36 di modificare i suoi prezzi in qualsiasi momento, tuttavia la merce sar\u00e0 fatturata sulla base dei prezzi indicati sul sito al momento della creazione dell&#8217;ordine e indicati nell&#8217;e-mail di conferma inviata da Boudoir 36 al CLIENTE.<\/p>\n<p>In caso di errore informatico, manuale, tecnico, o di qualsiasi altra natura che possa comportare un cambiamento sostanziale, non previsto da Boudoir 36, del prezzo di vendita al pubblico, che lo renda esorbitante o chiaramente irrisorio, l\u2019ordine d\u2019acquisto sar\u00e0 considerato non valido e annullato e l\u2019importo versato dal CLIENTE sar\u00e0 rimborsato entro 14 gg. dal giorno dell&#8217;annullamento.<\/li>\n<li>\n<h3>ARTICOLO 7 &#8211; Diritto di recesso<\/h3>\n<p>Ai sensi e per gli effetti del Codice del Consumo, cos\u00ec come modificato dal D.Lgs. n.21\/2014, al CLIENTE \u00e8 data facolt\u00e0 di esercitare il diritto di recesso, senza alcuna penalit\u00e0 e senza specificarne il motivo, entro 14 giorni di calendario dalla data di consegna del bene acquistato. Per avvalersi di tale diritto, il CLIENTE dovr\u00e0 inviare, entro i termini indicati, un messaggio di posta elettronica all\u2019indirizzo <a href=\"mailto:ecommerce@boudoir36.it\">ecommerce@boudoir36.it<\/a> oppure una lettera a mezzo raccomandata a.r., in cui vengano indicati i propri dati, e cio\u00e8 Nome, Cognome, Indirizzo, Numero d\u2019ordine, telefono, descrizione del\/i prodotto\/i, eventuali codici IBAN e SWIFT, nonch\u00e9 l\u2019intestatario del conto corrente dove viene chiesto di effettuare il bonifico per il rimborso.<\/p>\n<p>Non appena inviata tale comunicazione, il CLIENTE dovr\u00e0 spedire, a proprie spese e con un corriere di propria scelta, il prodotto che intende restituire, includendo nella spedizione un modulo (vedi sotto) con i propri dati che devono essere gli stessi di quelli inviati nella comunicazione di avvalersi del diritto di recesso.<\/p>\n<p>I costi diretti della restituzione dei prodotti sono a carico del CLIENTE. Il prodotto reso dovr\u00e0 pervenire a Boudoir 36 entro al massimo 14 giorni di calendario dalla data in cui ha comunicato il recesso. Una volta ricevuto il prodotto reso, Boudoir 36 proceder\u00e0, al rimborso relativo al prezzo pagato per il prodotto\/i per il\/i quale\/i si \u00e8 esercitato il diritto di recesso, entro 14 giorni di calendario dal giorno in cui \u00e8 stata comunicata la decisione del recesso, a patto che il bene oggetto del recesso sia pervenuto alla societ\u00e0, o sia stata fornita prova inequivocabile dell&#8217;avvenuta spedizione tramite corriere.<\/p>\n<p>Il cliente sar\u00e0 ritenuto responsabile, e quindi non risarcibile, per la diminuzione di valore dei beni risultante da una manipolazione diversa da quella strettamente necessaria a stabilire la natura e le caratteristiche del bene. Per i prodotti ad uso personale, per motivi igienici e sanitari NON \u00e8 possibile esercitare il diritto di recesso. I prodotti confezionati in cellophane NON possono essere restituiti se privi di tale protezione.<\/p>\n<p><strong>La merce dovr\u00e0 essere rispedita a:<\/strong><\/p>\n<address>Boudoir 36 di Alessandria Antonino Sebastiano<br \/>\nVia Santa Filomena, 36<br \/>\n95129 Catania (CT)<\/address>\n<p>Tutti i rischi relativi al trasporto del prodotto reso sono a carico del CLIENTE.<\/p>\n<p>La merce dovr\u00e0 essere restituita integra, nella confezione originale, completa in tutte le sue parti (compresi imballo ed eventuale dotazione accessoria) e completo della documentazione fiscale annessa. Fatta salva la facolt\u00e0 di verificare il rispetto di quanto sopra, Boudoir 36 provveder\u00e0 a rimborsare l&#8217;importo dei prodotti oggetto del recesso entro un termine massimo di 14 giorni, comprensivo degli eventuali costi di spedizione iniziale. Come previsto dall&#8217;art. 56 comma 3 del D.Lgs 206\/2005, modificato dal D.lgs 21\/2014, Boudoir 36 pu\u00f2 sospendere il rimborso fino al ricevimento dei beni oppure fino all&#8217;avvenuta dimostrazione da parte del CLIENTE di aver rispedito i beni a Boudoir 36.<\/p>\n<p>Boudoir 36 eseguir\u00e0 il rimborso utilizzando il mezzo scelto dal CLIENTE in fase di comunicazione di recesso. Nel caso di rimborso effettuato tramite bonifico, e qualora il CLIENTE intenda esercitare il proprio diritto di recesso, dovr\u00e0 fornire a Boudoir 36, tramite messaggio di posta elettronica all\u2019indirizzo <a href=\"mailto:ecommerce@boudoir36.it\">ecommerce@boudoir36.it<\/a>, le coordinate bancarie: codici IBAN e SWIFT necessari all&#8217;effettuazione del rimborso, da parte di Boudoir 36.<\/p>\n<p>Il CLIENTE potr\u00e0 esercitare il diritto di recesso anche inviando una qualsiasi dichiarazione esplicita contenente la decisione di recedere dal contratto oppure alternativamente trasmettere il modulo di recesso tipo, di cui all&#8217;Allegato I, parte B, D.Lgs 21\/2014 (non obbligatorio) il cui testo viene di seguito riportato:<\/p>\n<h4><strong><a href=\"http:\/\/www.boudoir36.it\/wp-content\/uploads\/2015\/06\/mod-diritto-di-recesso-boudoir36.pdf\" target=\"_blank\">Scarica il modulo di recesso tipo ai sensi dell\u2019art. 49, comma 1, lett. h)<\/a><\/strong><\/h4>\n<\/li>\n<li>\n<h3>ARTICOLO 8 &#8211; Garanzia legale di conformit\u00e0<\/h3>\n<p>In caso di ricezione di prodotti non conformi agli ordini o difettosi, il CLIENTE ha diritto al ripristino senza spese della conformit\u00e0 del prodotto mediante riparazione o sostituzione del prodotto. Il CLIENTE pu\u00f2 esercitare tale diritto se ha operato l\u2019acquisto in qualit\u00e0 di \u201cconsumatore\u201d. Inoltre il CLIENTE pu\u00f2 esercitare tale diritto se il difetto si manifesta entro il termine di due anni dalla consegna del bene e denuncia il difetto a Boudoir 36 entro due mesi dalla scoperta.<\/p>\n<p>Nel caso in cui il CLIENTE riscontri un difetto di conformit\u00e0 sui beni acquistati da Boudoir 36 nel corso del periodo di validit\u00e0 della Garanzia Legale, il CLIENTE deve mettersi in contatto con Boudoir 36 tramite messaggio di posta elettronica all\u2019indirizzo <a href=\"mailto:ecommerce@boudoir36.it\">ecommerce@boudoir36.it<\/a> o chiamando il numero telefonico <a href=\"tel:+390957152358\">+39 095 7152358<\/a>.<\/p>\n<p>Nei limiti consentiti dalla legge, Boudoir 36 declina ogni responsabilit\u00e0 nel caso in cui il prodotto consegnato non rispetti la legislazione del paese di consegna diverso dall&#8217;Italia.<\/li>\n<li>\n<h3>ARTICOLO 9 &#8211; Modalit\u00e0 di consegna<\/h3>\n<p>I prodotti saranno consegnati tramite corriere espresso all&#8217;indirizzo indicato dal CLIENTE al momento dell&#8217;ordine entro e non oltre 30gg. dalla data di ricezione da parte del CLIENTE dell&#8217;e-mail di conferma ordine inviata da Boudoir 36.<\/p>\n<p>Per ogni ordine effettuato sul sito <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a>, Boudoir 36 emette corrispettivo di vendita (nota di spedizione) della merce spedita. La fattura relativa ai prodotti acquistati dai privati non viene emessa in quanto trattasi di operazioni di vendita non soggette all&#8217;obbligo di certificazione fiscale ai sensi dell&#8217;articolo 22 comma 1 n 1 del Dpr 633 del 1972 e dell&#8217;articolo 2 del Dpr 696 del 1996. A tutti i CLIENTI viene inviato un riepilogo ordine che ha lo stesso valore fiscale e legale di uno scontrino tradizionale. La fattura \u00e8 disponibile a richiesta in fase di compilazione dell\u2019ordine, successivamente all&#8217;evasione dell&#8217;ordine, il CLIENTE ricever\u00e0 la fattura tramite messaggio di posta elettronica. La fattura conterr\u00e0 le informazioni fornite dal CLIENTE durante la procedura di acquisto. Dopo l&#8217;emissione della fattura, non sar\u00e0 possibile apportare alcuna modifica ai dati indicati nella stessa. Non \u00e8 possibile richiedere fattura dopo aver completato l\u2019ordine senza aver spuntato l\u2019apposita casella \u201cRichiesta Fattura\u201d.<\/li>\n<li>\n<h3>ARTICOLO 10 &#8211; Responsabilit\u00e0<\/h3>\n<p>Boudoir 36 non si assume alcuna responsabilit\u00e0 per disservizi imputabili a causa di forza maggiore o caso fortuito, anche ove dipendenti da malfunzionamenti e disservizi della rete Internet, nel caso in cui non riesca a dare esecuzione all&#8217;ordine nei tempi previsti dal contratto.<\/li>\n<li>\n<h3>ARTICOLO 11 &#8211; Accesso al sito<\/h3>\n<p>Il CLIENTE ha diritto di accedere al sito per la consultazione e l&#8217;effettuazione degli acquisti. Non \u00e8 consentito alcun altro utilizzo, in particolare commerciale, del sito o del suo contenuto. L&#8217;integrit\u00e0 degli elementi di questo sito, che siano sonori o visivi, e la relativa tecnologia utilizzata rimangono di propriet\u00e0 di Boudoir 36 e sono protetti dal diritto di propriet\u00e0 intellettuale.<\/li>\n<li>\n<h3>ARTICOLO 12 &#8211; Cookies<\/h3>\n<p>Il sito web <a href=\"http:\/\/www.boudoir36.it\">www.boudoir36.it<\/a> utilizza i &#8221;cookies&#8221;. I cookies sono file elettronici che registrano informazioni relative alla navigazione del CLIENTE nel sito (pagine consultate, data ed ora della consultazione, ecc..) e che permettono a Boudoir 36 di offrire un servizio personalizzato ai propri clienti.<\/p>\n<p>Boudoir 36 informa il CLIENTE della possibilit\u00e0 di disattivare la creazione di tali file, accedendo al proprio menu di configurazione Internet. Resta inteso che questo potrebbe impedire al CLIENTE di procedere all&#8217;acquisto on line.<\/li>\n<li>\n<h3>ARTICOLO 13 &#8211; Integralit\u00e0<\/h3>\n<p>Le presenti condizioni generali di vendita sono costituite dalla totalit\u00e0 delle clausole che le compongono. Se una o pi\u00f9 disposizioni delle presenti condizioni generali di vendita \u00e8 considerata non valida o dichiarata tale ai sensi della legge, della regolamentazione o in seguito a una decisione da parte di un tribunale avente giurisdizione, le altre disposizioni continueranno ad avere pieno vigore ed efficacia.<\/li>\n<li>\n<h3>ARTICOLO 14 &#8211; Legge applicabile e Foro competente<\/h3>\n<p>Le presenti condizioni generali di vendita sono sottoposte alla legge italiana.<\/p>\n<p>Ogni controversia che non trova soluzione amichevole sar\u00e0 sottoposta alla competenza esclusiva del Tribunale di Catania.<\/p>\n<p>In ogni caso, \u00e8 possibile ricorrere facoltativamente alle procedure di mediazione di cui al D.lgs 28\/2010, per la risoluzione di eventuali controversie insorte nell&#8217;interpretazione e nell&#8217;esecuzione delle presenti condizioni di vendita.<\/p>\n<p><strong>Condizioni generali di vendita aggiornate al 30 ottobre 2015.<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Disposizioni generali Le presenti condizioni sono valide esclusivamente tra la ditta individuale Boudoir 36 di Alessandria Antonino Sebastiano, con sede legale in Via Santa Filomena 36, 95129 Catania, Italia, REA CT-287036, P.IVA 04306840879, C.F. LSSNNN71C30C351R di seguito denominata \u201cBoudoir 36\u201d e qualsiasi persona, di seguito denominata \u201cCLIENTE\u201d, che effettua acquisti online sul sito internet www.boudoir36.it, accedendovi in maniera diretta o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Condizioni generali di vendita - Boudoir 36<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condizioni generali di vendita - Boudoir 36\" \/>\n<meta property=\"og:description\" content=\"Disposizioni generali Le presenti condizioni sono valide esclusivamente tra la ditta individuale Boudoir 36 di Alessandria Antonino Sebastiano, con sede legale in Via Santa Filomena 36, 95129 Catania, Italia, REA CT-287036, P.IVA 04306840879, C.F. LSSNNN71C30C351R di seguito denominata \u201cBoudoir 36\u201d e qualsiasi persona, di seguito denominata \u201cCLIENTE\u201d, che effettua acquisti online sul sito internet www.boudoir36.it, accedendovi in maniera diretta o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/\" \/>\n<meta property=\"og:site_name\" content=\"Boudoir 36\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Boudoir-36-325813206923\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-03T11:11:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@boudoir36\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/condizioni-di-vendita\\\/\",\"url\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/condizioni-di-vendita\\\/\",\"name\":\"Condizioni generali di vendita - Boudoir 36\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/#website\"},\"datePublished\":\"2015-04-07T11:27:57+00:00\",\"dateModified\":\"2015-11-03T11:11:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/condizioni-di-vendita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/condizioni-di-vendita\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/condizioni-di-vendita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condizioni generali di vendita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/#website\",\"url\":\"https:\\\/\\\/www.boudoir36.it\\\/\",\"name\":\"Boudoir 36\",\"description\":\"Profumeria Artistica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.boudoir36.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condizioni generali di vendita - Boudoir 36","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/","og_locale":"it_IT","og_type":"article","og_title":"Condizioni generali di vendita - Boudoir 36","og_description":"Disposizioni generali Le presenti condizioni sono valide esclusivamente tra la ditta individuale Boudoir 36 di Alessandria Antonino Sebastiano, con sede legale in Via Santa Filomena 36, 95129 Catania, Italia, REA CT-287036, P.IVA 04306840879, C.F. LSSNNN71C30C351R di seguito denominata \u201cBoudoir 36\u201d e qualsiasi persona, di seguito denominata \u201cCLIENTE\u201d, che effettua acquisti online sul sito internet www.boudoir36.it, accedendovi in maniera diretta o [&hellip;]","og_url":"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/","og_site_name":"Boudoir 36","article_publisher":"https:\/\/www.facebook.com\/Boudoir-36-325813206923","article_modified_time":"2015-11-03T11:11:26+00:00","twitter_card":"summary_large_image","twitter_site":"@boudoir36","twitter_misc":{"Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/","url":"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/","name":"Condizioni generali di vendita - Boudoir 36","isPartOf":{"@id":"https:\/\/www.boudoir36.it\/#website"},"datePublished":"2015-04-07T11:27:57+00:00","dateModified":"2015-11-03T11:11:26+00:00","breadcrumb":{"@id":"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.boudoir36.it\/it\/condizioni-di-vendita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.boudoir36.it\/it\/"},{"@type":"ListItem","position":2,"name":"Condizioni generali di vendita"}]},{"@type":"WebSite","@id":"https:\/\/www.boudoir36.it\/#website","url":"https:\/\/www.boudoir36.it\/","name":"Boudoir 36","description":"Profumeria Artistica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.boudoir36.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/pages\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":13,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/pages\/29\/revisions"}],"predecessor-version":[{"id":1824,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/pages\/29\/revisions\/1824"}],"wp:attachment":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/media?parent=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}