{"id":2517,"date":"2023-04-18T00:57:07","date_gmt":"2023-04-17T22:57:07","guid":{"rendered":"https:\/\/www.boudoir36.it\/?p=2517"},"modified":"2023-04-18T00:58:40","modified_gmt":"2023-04-17T22:58:40","slug":"amado-mio-amore-senza-fine","status":"publish","type":"post","link":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/","title":{"rendered":"Amado Mio &#8211; Amore Senza Fine"},"content":{"rendered":"<p class=\"p1\">Correvano gli anni venti, erano anni ruggenti e folli allo stesso tempo, la grande guerra era ormai un ricordo e dappertutto si tornava ad una parvenza di normalit\u00e0. Negli Stati Uniti il jazz impazzava, mentre le donne, flappers, gar\u00e7onne e maschiette, iniziavano a voler uscire dall\u2019ombra nella quale l\u2019universo maschile le aveva da sempre relegate. Nel frattempo il mondo cambiava aspetto seguendo i dettami del nuovo gusto, l\u2019art d\u00e9co, definitivamente trionfante con l\u2019esposizione internazionale di Parigi.<\/p>\n<p class=\"p1\">Tutto ci\u00f2 era solo un\u2019eco in una Catania, provincia siciliana, che nonostante si atteggiasse a citt\u00e0, era poco pi\u00f9 di un sobborgo rispetto alle grandi metropoli internazionali.<\/p>\n<p class=\"p1\">All\u2019ombra dell\u2019Elefante e dell\u2019Etna, simboli della citt\u00e0, due adolescenti, Giuseppina e Sebastiano, si guardavano da tempo tra un timido sorriso ed uno sguardo abbassato. Fino a quando, un giorno, Sebastiano decise di dichiararsi ufficialmente. Indossato il vestito della domenica, armato di coraggio, sceglie amorevolmente una rosa dal fioraio e si reca al negozio di dischi dove lavorava la giovane donna di cui si era infatuato. Alla chiusura Giuseppina fa finta di non aver capito e svolta velocemente verso casa. Allora lui la insegue, la raggiunge e le offre la rosa. Lei sorride e scruta furtivamente il suo pretendente in tutte le direzioni, per carpire qualche dettaglio che potesse dire qualcosa in pi\u00f9 sul suo carattere e sulla sua condizione. Lo sguardo si sofferma al taschino della giacca, dal quale svettano noncuranti due piccoli sigari. L\u2019incontro fu galeotto e da l\u00ec a poco Giuseppina e Sebastiano si fidanzarono ufficialmente, fino a coronare il loro amore col matrimonio.<\/p>\n<p class=\"p1\">Nel tempo, tutte le volte che Giuseppina voleva stuzzicare amorevolmente il marito, tirava in gioco il racconto del loro primo incontro, dicendo che Sebastiano era stato tanto amorevole nell\u2019offrirle una rosa, quanto incauto nel portare con s\u00e9 i suoi sigari che avevano coperto, col loro sentore, il delicato profumo della rosa. A quel punto Sebastiano controbatteva sempre dicendo che non era possibile, perch\u00e9 i sigari erano spenti ed inoltre lui aveva accuratamente scelto per lei la rosa pi\u00f9 profumata!<\/p>\n<p class=\"p1\">Questo episodio \u00e8 un esempio lampante di come la realt\u00e0 sia spesso percepita in modi differenti e che nel ricordo rimane sempre la traccia del personale punto di vista.<\/p>\n<p class=\"p1\">Ho sentito questo racconto innumerevoli volte direttamente da Giuseppina, mia nonna, considerato che Sebastiano, mio nonno, era gi\u00e0 morto due anni prima che io nascessi. A distanza di circa un secolo da quel fatidico incontro ho voluto donare un nuovo equilibrio ai due punti di vista dei miei nonni, per trovare l\u2019accordo perfetto tra la rosa e il tabacco, tra la delicatezza dello spirito maschile di mio nonno e la femminilit\u00e0 senza fronzoli di mia nonna.<\/p>\n<p class=\"p1\">Ho voluto che il nome del profumo fosse legato alla musica, per ricordare il luogo del loro primo incontro. Ho cercato tra i nomi delle canzoni dell\u2019epoca, ma nessuno ha acceso il mio immaginario. Poi mi \u00e8 venuta in mente Rita Hayworth con la sua splendida interpretazione di Amado Mio in Gilda. Sono andato a rivedere la scena del film e mi ha subito convinto. Forse perch\u00e9 ho sentito il racconto solo da mia nonna, con un tono tra l\u2019ironico ed il nostalgico, con la giusta dose di malinconia che solo il tempo pu\u00f2 rendere contemporaneamente dolce e struggente. Credo che questa canzone, nonostante lontana cronologicamente pi\u00f9 di un decennio dal loro incontro, possa interpretare correttamente l\u2019equilibrio tra la femminilit\u00e0 della rosa, la dolcezza rude del tabacco, l\u2019innocenza maliziosa dell\u2019incontro di due adolescenti, la sensualit\u00e0 sognante di una coppia nascente, la morbidezza confortante di un ricordo del passato che \u00e8 stato unico e totalizzante, ma che non torner\u00e0 mai pi\u00f9.<\/p>\n<p class=\"p1\">Amado Mio irrompe nell\u2019aria con un accordo verde e fiorito in cui i toni scuri e liquorosi di una rosa rossa si intrecciano con la linfa delle sue foglie, ma anche con l\u2019oscurit\u00e0 terrosa di un geranio dalle sfaccettature metalliche, fruttate e sotterranee. Gi\u00e0 nelle note di testa il tabacco viene annunciato dal sentore aromatico ed ambrato della salvia sclarea, ma si esprime appieno nella dolcezza mielata del fondo in cui la fava tonka, l\u2019elicriso e l\u2019assoluta di grano conferiscono sentori golosi, agresti e profondi. Note legnose di cedro e vetiver conferiscono struttura al fondo che giace su un letto di note ambrate e muschiate, setose e fruttate.<\/p>\n<p class=\"p1\">Da un punto di vista tecnico ho cercato di costruire i due accordi fondamentali in maniera verticale, in modo da rendere l\u2019idea di un vortice, quello dell\u2019amore, che nel suo turbinio lascia sfuggire le caratteristiche delle due anime rendendole per\u00f2 inseparabili ed imprescindibili. Due anime disciolte ed instillate in un unico liquido, racchiuse in un corpo, quello di un flacone rosso come la fiamma dell\u2019amore, ma trasparente come la sua purezza.<\/p>\n<p class=\"p3\"><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Antonio Alessandria<\/em><\/p>\n<p class=\"p1\">Amado Mio \u00e8 la decima fragranza della linea Antonio Alessandria Parfums<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Correvano gli anni venti, erano anni ruggenti e folli allo stesso tempo, la grande guerra era ormai un ricordo e dappertutto si tornava ad una parvenza di normalit\u00e0. Negli Stati Uniti il jazz impazzava, mentre le donne, flappers, gar\u00e7onne e maschiette, iniziavano a voler uscire dall\u2019ombra nella quale l\u2019universo maschile le aveva da sempre relegate. Nel frattempo il mondo cambiava [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":2509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[146],"tags":[],"class_list":["post-2517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amado Mio - Amore Senza Fine - Boudoir 36<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amado Mio - Amore Senza Fine - Boudoir 36\" \/>\n<meta property=\"og:description\" content=\"Correvano gli anni venti, erano anni ruggenti e folli allo stesso tempo, la grande guerra era ormai un ricordo e dappertutto si tornava ad una parvenza di normalit\u00e0. Negli Stati Uniti il jazz impazzava, mentre le donne, flappers, gar\u00e7onne e maschiette, iniziavano a voler uscire dall\u2019ombra nella quale l\u2019universo maschile le aveva da sempre relegate. Nel frattempo il mondo cambiava [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/\" \/>\n<meta property=\"og:site_name\" content=\"Boudoir 36\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Boudoir-36-325813206923\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T22:57:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-17T22:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.boudoir36.it\/wp-content\/uploads\/2023\/04\/AmadoMio-Mag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Alessandria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@boudoir36\" \/>\n<meta name=\"twitter:site\" content=\"@boudoir36\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Alessandria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/\"},\"author\":{\"name\":\"Antonio Alessandria\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/#\\\/schema\\\/person\\\/82abc7ac3795a19c0b1bab4c61ea6a04\"},\"headline\":\"Amado Mio &#8211; Amore Senza Fine\",\"datePublished\":\"2023-04-17T22:57:07+00:00\",\"dateModified\":\"2023-04-17T22:58:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/\"},\"wordCount\":822,\"image\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.boudoir36.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/AmadoMio-Mag.jpg\",\"articleSection\":[\"Magazine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/\",\"url\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/\",\"name\":\"Amado Mio - Amore Senza Fine - Boudoir 36\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.boudoir36.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/AmadoMio-Mag.jpg\",\"datePublished\":\"2023-04-17T22:57:07+00:00\",\"dateModified\":\"2023-04-17T22:58:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/#\\\/schema\\\/person\\\/82abc7ac3795a19c0b1bab4c61ea6a04\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.boudoir36.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/AmadoMio-Mag.jpg\",\"contentUrl\":\"https:\\\/\\\/www.boudoir36.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/AmadoMio-Mag.jpg\",\"width\":1000,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/amado-mio-amore-senza-fine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amado Mio &#8211; Amore Senza Fine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/#website\",\"url\":\"https:\\\/\\\/www.boudoir36.it\\\/\",\"name\":\"Boudoir 36\",\"description\":\"Profumeria Artistica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.boudoir36.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.boudoir36.it\\\/#\\\/schema\\\/person\\\/82abc7ac3795a19c0b1bab4c61ea6a04\",\"name\":\"Antonio Alessandria\",\"url\":\"https:\\\/\\\/www.boudoir36.it\\\/it\\\/author\\\/antonio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amado Mio - Amore Senza Fine - Boudoir 36","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/","og_locale":"it_IT","og_type":"article","og_title":"Amado Mio - Amore Senza Fine - Boudoir 36","og_description":"Correvano gli anni venti, erano anni ruggenti e folli allo stesso tempo, la grande guerra era ormai un ricordo e dappertutto si tornava ad una parvenza di normalit\u00e0. Negli Stati Uniti il jazz impazzava, mentre le donne, flappers, gar\u00e7onne e maschiette, iniziavano a voler uscire dall\u2019ombra nella quale l\u2019universo maschile le aveva da sempre relegate. Nel frattempo il mondo cambiava [&hellip;]","og_url":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/","og_site_name":"Boudoir 36","article_publisher":"https:\/\/www.facebook.com\/Boudoir-36-325813206923","article_published_time":"2023-04-17T22:57:07+00:00","article_modified_time":"2023-04-17T22:58:40+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/www.boudoir36.it\/wp-content\/uploads\/2023\/04\/AmadoMio-Mag.jpg","type":"image\/jpeg"}],"author":"Antonio Alessandria","twitter_card":"summary_large_image","twitter_creator":"@boudoir36","twitter_site":"@boudoir36","twitter_misc":{"Scritto da":"Antonio Alessandria","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/#article","isPartOf":{"@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/"},"author":{"name":"Antonio Alessandria","@id":"https:\/\/www.boudoir36.it\/#\/schema\/person\/82abc7ac3795a19c0b1bab4c61ea6a04"},"headline":"Amado Mio &#8211; Amore Senza Fine","datePublished":"2023-04-17T22:57:07+00:00","dateModified":"2023-04-17T22:58:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/"},"wordCount":822,"image":{"@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.boudoir36.it\/wp-content\/uploads\/2023\/04\/AmadoMio-Mag.jpg","articleSection":["Magazine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/","url":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/","name":"Amado Mio - Amore Senza Fine - Boudoir 36","isPartOf":{"@id":"https:\/\/www.boudoir36.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/#primaryimage"},"image":{"@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.boudoir36.it\/wp-content\/uploads\/2023\/04\/AmadoMio-Mag.jpg","datePublished":"2023-04-17T22:57:07+00:00","dateModified":"2023-04-17T22:58:40+00:00","author":{"@id":"https:\/\/www.boudoir36.it\/#\/schema\/person\/82abc7ac3795a19c0b1bab4c61ea6a04"},"breadcrumb":{"@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/#primaryimage","url":"https:\/\/www.boudoir36.it\/wp-content\/uploads\/2023\/04\/AmadoMio-Mag.jpg","contentUrl":"https:\/\/www.boudoir36.it\/wp-content\/uploads\/2023\/04\/AmadoMio-Mag.jpg","width":1000,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.boudoir36.it\/it\/amado-mio-amore-senza-fine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.boudoir36.it\/it\/"},{"@type":"ListItem","position":2,"name":"Amado Mio &#8211; Amore Senza Fine"}]},{"@type":"WebSite","@id":"https:\/\/www.boudoir36.it\/#website","url":"https:\/\/www.boudoir36.it\/","name":"Boudoir 36","description":"Profumeria Artistica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.boudoir36.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.boudoir36.it\/#\/schema\/person\/82abc7ac3795a19c0b1bab4c61ea6a04","name":"Antonio Alessandria","url":"https:\/\/www.boudoir36.it\/it\/author\/antonio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/posts\/2517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/comments?post=2517"}],"version-history":[{"count":1,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/posts\/2517\/revisions"}],"predecessor-version":[{"id":2518,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/posts\/2517\/revisions\/2518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/media\/2509"}],"wp:attachment":[{"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/media?parent=2517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/categories?post=2517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.boudoir36.it\/it\/wp-json\/wp\/v2\/tags?post=2517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}